{"id":1271,"date":"2019-10-21T10:20:13","date_gmt":"2019-10-21T08:20:13","guid":{"rendered":"https:\/\/licenceking.fr\/blog\/?p=1271"},"modified":"2019-10-21T10:24:14","modified_gmt":"2019-10-21T08:24:14","slug":"un-tableur-mais-pas-seulement-simplifiez-vous-la-vie-avec-excel-2019","status":"publish","type":"post","link":"https:\/\/licenceking.fr\/blog\/un-tableur-mais-pas-seulement-simplifiez-vous-la-vie-avec-excel-2019\/","title":{"rendered":"Un tableur mais pas seulement \u2013 Simplifiez-vous la vie avec Excel 2019 !"},"content":{"rendered":"<p>Un tableur intuitif et qui fonctionne bien est devenu indispensable dans la sph\u00e8re priv\u00e9e comme dans votre vie professionnelle. Utiliser Excel 2019 vous comblera de plaisir, car en plus des fonctions habituelles, Microsoft y a ajout\u00e9 de nouvelles fonctionnalit\u00e9s de documentation, de calcul et de gestion des donn\u00e9es, avec un tout nouveau design. Laissez-nous vous pr\u00e9senter <a href=\"https:\/\/licenceking.fr\/microsoft\/logiciel-individuel\/excel\/microsoft-excel-2019\">Excel 2019<\/a> !<\/p>\n<h3><strong>Une meilleure visualisation des donn\u00e9es dans Excel 2019<\/strong><\/h3>\n<p>Tout comme dans <a href=\"https:\/\/licenceking.fr\/blog\/word-2019-on-valide-les-nouvelles-fonctionnalites\/\">Word 2019<\/a>, Microsoft s&#8217;est donn\u00e9 la peine d&#8217;am\u00e9liorer et de moderniser l&#8217;ergonomie et l&#8217;apparence du logiciel dans la toute nouvelle version d&#8217;Excel \u2013 selon les standards de <a href=\"https:\/\/licenceking.fr\/microsoft\/windows\/windows-10\/\">Windows 10<\/a>, tout en incluant des \u00e9l\u00e9ments optiques bien connus d&#8216;<a href=\"https:\/\/licenceking.fr\/blog\/comparatif-des-versions-de-ms-office-2016\/\">Office 2016<\/a>. Pour ceux qui s&#8217;\u00e9taient habitu\u00e9s \u00e0 la pr\u00e9c\u00e9dente version sur l&#8217;interface Ribbon User, le tableur peut aussi \u00eatre utilis\u00e9 de cette mani\u00e8re pour \u00e9viter de chambouler vos habitudes.<\/p>\n<p>Un atout qui m\u00e9rite d&#8217;\u00eatre soulign\u00e9\u00a0: Excel 2019 enregistre vos habitudes et les met en relation les unes avec les autres\u00a0! Ainsi, le programme d\u00e9tecte les \u00e9l\u00e9ments fr\u00e9quemment utilis\u00e9s et les rend ensuite bien visibles. De plus, Excel 2019 nous convainc aussi avec des valeurs intrins\u00e8ques au logiciel \u2013 on y trouve par exemple une forme d&#8217;intelligence artificielle dans le Machine Learning d&#8217;Excel. La version de 2019 est capable d&#8217;analyser des ensembles de donn\u00e9es complexes, de les traduire en algorithme afin de pouvoir les retravailler apr\u00e8s. Vous verrez imm\u00e9diatement de quelle fa\u00e7on Excel 2019 est capable de vous simplifier consid\u00e9rablement la t\u00e2che et de placer votre productivit\u00e9 sur un tout autre niveau.<\/p>\n<p>En mati\u00e8re de visualisation, Excel dispose aussi d&#8217;un tout nouvel attirail. De la m\u00eame mani\u00e8re que Word 2019, vous pourrez utiliser dans Excel des vecteurs graphiques \u00e9volutifs et des mod\u00e8les 3D pour repr\u00e9senter vos r\u00e9sultats et am\u00e9liorer votre pr\u00e9sentation visuellement parlant. M\u00eame la conversion d&#8217;ic\u00f4nes en graphiques est possible, libre \u00e0 vous de configurer vous-m\u00eames leur forme, leur couleur et leur taille.<\/p>\n<h3><strong>Excel 2019 comporte de nouvelles formes et de nouveaux diagrammes<\/strong><\/h3>\n<p>Pour les calculs simples, nous utilisons soit notre t\u00eate soit une calculatrice. Mais quand on va au-del\u00e0 du calcul avec des plus et des moins, Excel est un auxiliaire utile pour obtenir des r\u00e9sultats fiables dans le domaine du commerce ou des statistiques. Avec des centaines de formules et de fonctions, Excel 2019 vous offre bien s\u00fbr les fonctions habituelles telles que SOMME, MOYENNE ou SI\/ALORS. Vous aurez en plus acc\u00e8s \u00e0 de nouvelles fonctionnalit\u00e9s qui vous donneront encore plus de possibilit\u00e9s pour vos analyses et vos calculs.<\/p>\n<p>La nouvelle fonction CHAINE DE TEXTE vous permet par exemple de relier entre elles un grand nombre de cellules avec jusqu&#8217;\u00e0 253 arguments. En compl\u00e9ment des nombreuses fonctions SI, il existe un SI.CONDITIONS qui permet de simplifier l\u2019imbrication de vos fonctions SI en v\u00e9rifiant si une ou plusieurs conditions sont remplies et en choisissant la valeur de la premi\u00e8re (vraie) condition. Pour d\u00e9terminer des valeurs minimales ou maximales d&#8217;une plage de cellules, Excel 2019 propose les fonctions MAX.SI.ENS et MIN.SI. Pour d\u00e9terminer les valeurs qui se correspondent dans une liste, vous pourrez utiliser SI.MULTIPLE qui permet de comparer jusqu&#8217;\u00e0 126 param\u00e8tres.<\/p>\n<p>Pour mieux visualiser vos r\u00e9sultats, utilisez les anciens et les nouveaux diagrammes\u00a0! Vous pourrez cr\u00e9er un planisph\u00e8re pour comparer facilement des valeurs relatives \u00e0 diff\u00e9rentes r\u00e9gions du monde, comme des pays, des codes postaux ou des municipalit\u00e9s. Avec le nouveau mod\u00e8le de graphique en entonnoir, vous pourrez repr\u00e9senter des valeurs relatives aux diff\u00e9rentes phases d&#8217;un processus comme par exemple un processus de vente. En r\u00e8gle g\u00e9n\u00e9rale, les valeurs deviennent de plus en plus petites, ce ce qui produit un diagramme en forme d&#8217;entonnoir.<\/p>\n<h3><strong><img loading=\"lazy\" class=\"alignnone size-full wp-image-1347\" src=\"https:\/\/lizenzking.de\/blog\/de\/wp-content\/uploads\/sites\/2\/2019\/10\/Excel-2019_2.jpg\" alt=\"Tabellenkalkulation und mehr - leicht gemacht mit Excel 2019!\" width=\"2400\" height=\"1600\" \/><\/strong><\/h3>\n<h3><strong>Excel est entr\u00e9 dans l&#8217;\u00e8re du num\u00e9rique<\/strong><\/h3>\n<p>Le recours \u00e0 l&#8217;intelligence artificielle n&#8217;est pas le seul progr\u00e8s, \u00e0 l&#8217;\u00e8re du num\u00e9rique. L&#8217;utilisation de programmes Office avec un stylet ou un touchpad est devenue incontournable. Avec le stylet de surface, Excel 2019 met diff\u00e9rents types d&#8217;\u00e9criture \u00e0 votre disposition. Que vous souhaitiez \u00e9crire, surligner ou mettre en avant une id\u00e9e, vous avec acc\u00e8s \u00e0 tout un attirail d&#8217;outils\u00a0: du surligneur au crayon \u00e0 papier en passant par les couleurs, les effets m\u00e9talliques et les effets d&#8217;encre, vous avez toute latitude pour utiliser le mode main libre digital \u00e0 votre guise. D&#8217;ailleurs la fonction mains libres peut fonctionner aussi bien avec un stylet qu&#8217;avec le doigt ou la souris.<\/p>\n<p>Comme pour tous les autres logiciels <a href=\"https:\/\/licenceking.fr\/blog\/telecharger-microsoft-office-2019-voila-comment-demasquer-les-licences-illegales\/\">Office 2019<\/a>, Excel 2019 voit son syst\u00e8me de v\u00e9rification des barri\u00e8res de s\u00e9curit\u00e9 nettement am\u00e9lior\u00e9. Avant de partager l&#8217;acc\u00e8s \u00e0 votre tableur avec d&#8217;autres utilisateurs, le syst\u00e8me de v\u00e9rification des barri\u00e8res de s\u00e9curit\u00e9 vous permet de vous assurer que le document est ais\u00e9ment lisible par tous et pourra \u00eatre retravaill\u00e9 sans difficult\u00e9.<\/p>\n<p>Mais ce n&#8217;est pas tout\u00a0! Microsoft en fait toujours plus pour les entreprises\u00a0: dans Outlook vous appr\u00e9ciez g\u00e9n\u00e9ralement le syst\u00e8me de protection contre la perte de donn\u00e9es (Data Loss Protection = DLP). Se basant sur une s\u00e9rie de directives pr\u00e9-d\u00e9finies, les contenus sont analys\u00e9s en temps r\u00e9el en fonction de donn\u00e9es pr\u00e9cises (par exemple le num\u00e9ro de votre carte de cr\u00e9dit, votre num\u00e9ro d&#8217;assur\u00e9 social, vos donn\u00e9es bancaires). La synchronisation des donn\u00e9es DLP depuis d&#8217;autres programmes Office est facilit\u00e9e par un traitement uniforme des donn\u00e9es critiques que vous voulez conserver dans Exchange, SharePoint ou encore OneDrive for Business.<\/p>\n<h3><strong>Des r\u00e9sultats encore meilleurs avec PivotTable &amp; Co.<\/strong><\/h3>\n<p>Excel est connu pour des r\u00e9sultats d&#8217;analyses puissants et flexibles que l&#8217;on doit \u00e0 ce qu&#8217;on appelle la PivotTable. Depuis que ce syst\u00e8me a \u00e9t\u00e9 ajout\u00e9 \u00e0 Excel en 2010 et \u00e0 Power Pivot en 2013, cette fonction a \u00e9t\u00e9 largement optimis\u00e9e. Dans Excel 2019, vous d\u00e9couvrirez d&#8217;autres am\u00e9liorations qui vous simplifieront encore plus la construction de mod\u00e8les de donn\u00e9es pertinents et efficaces. Vous pouvez par exemple vous lancer dans une mise en page standard, adapt\u00e9e \u00e0 vos besoins et \u00e0 vos exigences, avec PivotTable, pour retrouver rapidement et facilement des r\u00e9sultats r\u00e9currents. De plus, le programme vous permet la mise en relation rapide de documents et d\u00e9tecte automatiquement \u00e0 quel moment vous avez besoin de relier deux tableaux pour vos analyses. Un clic suffit \u00e0 Excel 2019 pour effectuer la mise en relation, cette fonction est donc utilisable \u00e0 tout moment.<\/p>\n<p>Au fait\u00a0: si vous \u00eates un utilisateur du service Business Analytics Power BI, vous pouvez d\u00e8s maintenant publier vos donn\u00e9es stock\u00e9es localement.<\/p>\n<h3><strong>Chez Licenceking, Excel 2019 est notre favori<\/strong><\/h3>\n<p>Les nombreuses am\u00e9liorations et les nouveaux outils d&#8217;Excel 2019 font appara\u00eet clairement que Microsoft a s\u00e9rieusement augment\u00e9 les performances de ses outils depuis 2019\u00a0: que ce soit pour le pack <a href=\"https:\/\/licenceking.fr\/microsoft\/office\/office-2019\/\">Office 2019<\/a> ou pour des applications isol\u00e9es indispensables \u00e0 tout PC, Excel 2019 vous permet de travailler ais\u00e9ment sur des masses de donn\u00e9es consid\u00e9rables du fait de l&#8217;ergonomie optimale et des outils les plus d\u00e9velopp\u00e9s. Jetez un \u0153il \u00e0 notre boutique en ligne\u00a0! Nous vous donnerons les meilleurs conseils sur les produits Office disponibles dans notre boutique.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un tableur intuitif et qui fonctionne bien est devenu indispensable dans la sph\u00e8re priv\u00e9e comme dans votre vie professionnelle. Utiliser Excel 2019 vous comblera de plaisir, car en plus des fonctions habituelles, Microsoft y a ajout\u00e9 de nouvelles fonctionnalit\u00e9s de documentation, de calcul et de gestion des donn\u00e9es, avec un tout nouveau design. Laissez-nous vous [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":1273,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[2,15],"tags":[],"_links":{"self":[{"href":"https:\/\/licenceking.fr\/blog\/wp-json\/wp\/v2\/posts\/1271"}],"collection":[{"href":"https:\/\/licenceking.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/licenceking.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/licenceking.fr\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/licenceking.fr\/blog\/wp-json\/wp\/v2\/comments?post=1271"}],"version-history":[{"count":3,"href":"https:\/\/licenceking.fr\/blog\/wp-json\/wp\/v2\/posts\/1271\/revisions"}],"predecessor-version":[{"id":1275,"href":"https:\/\/licenceking.fr\/blog\/wp-json\/wp\/v2\/posts\/1271\/revisions\/1275"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/licenceking.fr\/blog\/wp-json\/wp\/v2\/media\/1273"}],"wp:attachment":[{"href":"https:\/\/licenceking.fr\/blog\/wp-json\/wp\/v2\/media?parent=1271"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/licenceking.fr\/blog\/wp-json\/wp\/v2\/categories?post=1271"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/licenceking.fr\/blog\/wp-json\/wp\/v2\/tags?post=1271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}